{"id":6563,"date":"2018-04-19T19:10:12","date_gmt":"2018-04-19T17:10:12","guid":{"rendered":"http:\/\/nosade.com\/de\/?p=6563"},"modified":"2024-11-18T13:56:33","modified_gmt":"2024-11-18T12:56:33","slug":"nosade-venue-merzouga","status":"publish","type":"post","link":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/","title":{"rendered":"NOSADE Venue <br>Merzouga"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Sei famili\u00e4r untergebracht bevor Du Deine W\u00fcstentour in die weiten D\u00fcnen von Merzouga auf Deiner W\u00fcstentour mit NOSADE startest<\/h5>\n\n\n\n<p class=\"has-text-align-center\">Unser kleines Apartment mit Blick auf die ber\u00fchmten Sandd\u00fcnen von Merzouga erwartet Dich in modernem, komfortablem Design und einer traditionellen Architektur. Das Apartment verf\u00fcgt \u00fcber ein Queensize-Bett (160&#215;200), ein kleines Wohnzimmer mit einer Sitzecke, die in zwei zus\u00e4tzliche Einzelbetten (90&#215;200) umgewandelt werden kann, sowie ein luxuri\u00f6ses und ger\u00e4umiges Badezimmer. Die ber\u00fchmten D\u00fcnen von Merzouga liegen direkt vor der T\u00fcr. Und unsere Familie empf\u00e4ngt Dich herzlich mit authentischer Berber-Gastfreundschaft und leckeren frischen Speisen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Desert-View-Merzouga_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10681\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Desert-View-Merzouga_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10681\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Desert-View-Merzouga_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Desert-View-Merzouga_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Desert-View-Merzouga_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-View-Sunrise_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10549\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-View-Sunrise_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10549\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-View-Sunrise_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-View-Sunrise_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-View-Sunrise_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-01_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10677\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-01_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10677\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-01_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-01_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-01_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-00_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10676\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-00_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10676\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-00_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-00_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Apartment-Merzouga-00_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Merzouga-Desert-Accommodation_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10674\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Merzouga-Desert-Accommodation_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10674\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Merzouga-Desert-Accommodation_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Merzouga-Desert-Accommodation_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Merzouga-Desert-Accommodation_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-LivingSleeping_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10554\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-LivingSleeping_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10554\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-LivingSleeping_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-LivingSleeping_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-LivingSleeping_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-1_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10557\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-1_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10557\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-1_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-1_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room-1_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10558\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10558\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Room_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Sahara-Desert-Apartment-Merzouga_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10679\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Sahara-Desert-Apartment-Merzouga_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10679\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Sahara-Desert-Apartment-Merzouga_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Sahara-Desert-Apartment-Merzouga_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Sahara-Desert-Apartment-Merzouga_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bedroom_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10556\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bedroom_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10556\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bedroom_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bedroom_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bedroom_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-2_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10552\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-2_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10552\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-2_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-2_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-2_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-1_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10551\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-1_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10551\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-1_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-1_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Bathroom-1_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Outside_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10553\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Outside_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10553\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Outside_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Outside_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venues-Merzouga-Outside_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Room-with-a-view-Dunes-of-Merzouga_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10550\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Room-with-a-view-Dunes-of-Merzouga_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10550\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Room-with-a-view-Dunes-of-Merzouga_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Room-with-a-view-Dunes-of-Merzouga_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Room-with-a-view-Dunes-of-Merzouga_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nosade.com\/wp-content\/uploads\/Desert-of-Merzouga_Source-NOSADE.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-id=\"10555\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/Desert-of-Merzouga_Source-NOSADE-720x960.jpg\" alt=\"\" class=\"wp-image-10555\" srcset=\"https:\/\/nosade.com\/wp-content\/uploads\/Desert-of-Merzouga_Source-NOSADE.jpg 720w, https:\/\/nosade.com\/wp-content\/uploads\/Desert-of-Merzouga_Source-NOSADE-225x300.jpg 225w, https:\/\/nosade.com\/wp-content\/uploads\/Desert-of-Merzouga_Source-NOSADE-540x720.jpg 540w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>DEINE AUTHENTISCHE UNTERKUNFT IN MERZOUGA<\/strong><\/h3>\n\n\n\n<p class=\"has-text-align-center\">Unser NOSADE Venue hei\u00dft Dich in privater und famili\u00e4rer Atmosph\u00e4re, mit viel Ruhe und wundersch\u00f6ner Aussicht auf die ber\u00fchmten Sandd\u00fcnen des Erg Chebbi willkommen. Der Preis pro \u00dcbernachtung beginnt bei 85 EUR und beinhaltet ein traditionelles Fr\u00fchst\u00fcck. Dazu gebucht werden kann selbstverst\u00e4ndlich auch ein leckeres Abendessen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">G\u00c4STEBEWERTUNGEN<\/h5>\n\n\n<div class=\"rating-slider has-logo clearfix\" data-speed=\"9500\"><span class=\"logo\"><a href=\"https:\/\/www.airbnb.de\/rooms\/33283457\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/nosade.com\/wp-content\/uploads\/logos_extern\/airbnb_sh.png\" alt=\"\"><\/a><\/span><div class=\"slider\"><div class=\"slick clearfix\"><div class=\"slide\">\u201eUnser Aufenthalt in Anicas Riad war wundersch\u00f6n. F\u00fcr mich als Fotografin war die Unterkunft das reinste Paradies &#8211; soviele wundersch\u00f6ne Details, tolle moderne Einrichtung und in Kombination mit den vielen Pflanzen einfach traumhaft sch\u00f6n! Lena und Mustafa waren super gastfreundlich und haben uns tolle Tipps gegeben. Dieses Riad ist wirklich eine Oase und absolut empfehlenswert! Ich w\u00fcrde es jederzeit wieder buchen. (Vivian)\u201c<\/div><div class=\"slide\">\u201eWar f\u00fcr 4 N\u00e4chte zu Gast und es war einfach toll! Das Riad ist wundersch\u00f6n hergerichtet und im Zimmer findet man alles was man braucht. Mir wurden alle W\u00fcnsche erf\u00fcllt bevor ich \u00fcberhaupt wusste dass ich sie habe! Alle waren sehr bem\u00fcht mir den Aufenthalt so angenehm wie m\u00f6glich zu machen! Die Lage ist sehr gut, vor allem f\u00fcr Alleinreisende! Sehr sauber und gepflegt. Man f\u00fchlt sich sofort wie Zuhause! Ich m\u00f6chte mich auf jeden Fall f\u00fcr alles bedanken und kann es nicht erwarten wieder zu kommen!!! Also kurz gesagt: wenn ihr nach Marrakech kommt, dann auf jeden Fall zu Anica &amp; Yidir!!!!!!!! (Anna)\u201c<\/div><div class=\"slide\">\u201eWir hatten einen Topaufenthalt im Riad. Das Zimmer war etwas kalt, aber wir bekamen einen elektr. Heizk\u00f6rper f\u00fcr die Zeit u W\u00e4rmflaschen. Das Riad liegt zentral u ist angehm ruhig. Lena und Mustafa haben uns rundum gut versorgt! Die Terrasse ist ein Highlight. (Viktoria)\u201c<\/div><div class=\"slide\">\u201eEs war wundesch\u00f6n. Ich konnte in Ruhe arbeiten und die Mitarbeiter haben alles m\u00f6glich gemacht um was man gebeten hat. Das Hostel ist perfekt um nach einem Tag in der Medina herunter zu fahren. Wenn die ganze Stadt schon sehr bunt ist, hat es einen sehr beruhigenden Effekt wenn alles wei\u00df ist. Ich komme gerne wieder! Dankesch\u00f6n \ud83d\ude42 (Nadine)\u201c<\/div><\/div><span class=\"more clearfix\"><a href=\"https:\/\/www.airbnb.de\/rooms\/33283457\" target=\"_blank\">MEHR AUF AIRBNB<\/a><\/span><\/div><\/div>\n\n\n\n<div class=\"center\" style=\"text-align: center;\"><div class=\"btn-container \"><a class=\"organic-btn  blue-btn small-btn \" href=\"https:\/\/nosade.com\/de\/wuestentouren\/\"><span class=\"btn-holder\">Sieh Dir hier unsere W\u00fcsten-Packages an!<\/span><\/a><\/div><\/div>\n\n\n\n<div>&nbsp;<\/div>\n\n\n\n<p class=\"has-text-align-center\"><strong>Schicke uns bei Interesse Deine individuelle und unverbindliche Buchungsanfrage.<br>Wir beraten Dich gern!<br>\u2764<br><\/strong><\/p>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f11237-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"11237\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/posts\/6563#wpcf7-f11237-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"11237\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f11237-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div id=\"booking\">\n\t<h2>Buchungsanfrage <span id=\"booking-contact\"><a href=\"mailto:info@nosade.com\"><i class=\"fa fa-envelope\" aria-hidden=\"true\"><\/i><\/a><a href=\"tel:0493068075494\"><i class=\"fa fa-phone\" aria-hidden=\"true\"><\/i><\/a><a href=\"javascript:void(Tawk_API.toggle());\"><i class=\"fa fa-comments\" aria-hidden=\"true\"><\/i><\/a><\/span>\n\t<\/h2>\n\t<p><a href=\"tel:+493068075494\">Rufe uns an<\/a> f\u00fcr mehr Information & Inspiration oder schicke uns jetzt Deine unverbindliche Buchungsanfrage.\n\t<\/p>\n\t<div class=\"organic-column one-half\">\n\t\t<p><strong>Vorname<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>E-Mail<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Anreise<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"date-getting-there\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" placeholder=\"mm\/dd\/yy\" value=\"\" type=\"date\" name=\"date-getting-there\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Personen<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"persons\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"20\" step=\"1\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"persons\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Aktionscode<\/strong>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"code\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"code\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"organic-column one-half last\">\n\t\t<p><strong>Nachname<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Telefon<\/strong>\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Abreise<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"date-departure\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-date\" aria-invalid=\"false\" placeholder=\"mm\/dd\/yy\" value=\"\" type=\"date\" name=\"date-departure\" \/><\/span>\n\t\t<\/p>\n\t\t<p><strong>Zimmer<\/strong>*\n\t\t<\/p>\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"rooms\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"20\" step=\"1\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"rooms\" \/><\/span>\n\t\t<\/p>\n\t\t<p><span id=\"wpcf7-6a56d800dd159-wrapper\" class=\"wpcf7-form-control-wrap birthdate-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a56d800dd159-field\" class=\"hp-message\">Bitte lasse dieses Feld leer.<\/label><input id=\"wpcf7-6a56d800dd159-field\"  placeholder=\"mm\/dd\/yy\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"birthdate\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span><br \/>\n<span id=\"wpcf7-6a56d800dd194-wrapper\" class=\"wpcf7-form-control-wrap sex-wrap\" style=\"display:none !important; visibility:hidden !important;\"><label for=\"wpcf7-6a56d800dd194-field\" class=\"hp-message\">Bitte lasse dieses Feld leer.<\/label><input id=\"wpcf7-6a56d800dd194-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"sex\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"new-password\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"clearboth\">\n\t<\/div>\n\t<p><strong>Nachricht<\/strong>*\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"newsletter[]\" value=\"Melde Dich an zu unserem fabelhaften Newsletter und verpasse keine unserer Sonderaktionen und exklusiven Specials!\" \/><span class=\"wpcf7-list-item-label\">Melde Dich an zu unserem fabelhaften Newsletter und verpasse keine unserer Sonderaktionen und exklusiven Specials!<\/span><\/span><\/span><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"terms\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first last\"><input type=\"checkbox\" name=\"terms[]\" value=\"Ja\" \/><span class=\"wpcf7-list-item-label\">Ja<\/span><\/span><\/span><\/span>, ich habe die <a href=\"http:\/\/nosade.com\/de\/agb\/\" target=\"_blank\">AGB<\/a> von NOSADE gelesen und akzeptiert. <strong>*<\/strong>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-433\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-433\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ich habe die <a href=\"\/de\/datenschutzerklaerung\/\" target=\"_blank\">Datenschutzerkl\u00e4rung<\/a> zur Kenntnis genommen. Ich stimme zu, dass meine Angaben zur Kontaktaufnahme und f\u00fcr R\u00fcckfragen dauerhaft gespeichert werden.<strong>*<\/strong>\n\t<\/p>\n\t<p style=\"font-size:12px;\">* = Pflichtfelder<br \/>\nHinweis: Sie k\u00f6nnen Ihre Einwilligung jederzeit mit Wirkung auf die Zukunft, per Mail an info@nosade.com widerrufen.\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Jetzt anfragen\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\">\u2764<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DU PLANST EINE REISE NACH MERZOUGA?<br \/>\nWohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!<\/p>\n","protected":false},"author":1,"featured_media":6564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-6563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-venues-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NOSADE Venue Merzouga - NOSADE<\/title>\n<meta name=\"description\" content=\"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NOSADE Venue Merzouga - NOSADE\" \/>\n<meta property=\"og:description\" content=\"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/\" \/>\n<meta property=\"og:site_name\" content=\"NOSADE\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-19T17:10:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-18T12:56:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nosade\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"nosade\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/\",\"url\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/\",\"name\":\"NOSADE Venue Merzouga - NOSADE\",\"isPartOf\":{\"@id\":\"https:\/\/nosade.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg\",\"datePublished\":\"2018-04-19T17:10:12+00:00\",\"dateModified\":\"2024-11-18T12:56:33+00:00\",\"author\":{\"@id\":\"https:\/\/nosade.com\/de\/#\/schema\/person\/3a5e11047087029c7cd54f0a51e6695a\"},\"description\":\"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!\",\"breadcrumb\":{\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage\",\"url\":\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg\",\"contentUrl\":\"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg\",\"width\":1800,\"height\":720,\"caption\":\"nosade-venue-merzouga_source-nosade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nosade.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venues\",\"item\":\"https:\/\/nosade.com\/de\/venues-de\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NOSADE Venue Merzouga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nosade.com\/de\/#website\",\"url\":\"https:\/\/nosade.com\/de\/\",\"name\":\"NOSADE\",\"description\":\"Yoga Reisen & Sahara W\u00fcstentouren f\u00fcr Nomadenherzen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nosade.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/nosade.com\/de\/#\/schema\/person\/3a5e11047087029c7cd54f0a51e6695a\",\"name\":\"nosade\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/nosade.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4beed8cfa39a37428b42f05072eedffb15a830a13cdeebc0e9fff810ca432ae2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4beed8cfa39a37428b42f05072eedffb15a830a13cdeebc0e9fff810ca432ae2?s=96&d=mm&r=g\",\"caption\":\"nosade\"},\"url\":\"https:\/\/nosade.com\/de\/author\/nosade\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NOSADE Venue Merzouga - NOSADE","description":"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/","og_locale":"de_DE","og_type":"article","og_title":"NOSADE Venue Merzouga - NOSADE","og_description":"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!","og_url":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/","og_site_name":"NOSADE","article_published_time":"2018-04-19T17:10:12+00:00","article_modified_time":"2024-11-18T12:56:33+00:00","og_image":[{"width":1800,"height":720,"url":"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg","type":"image\/jpeg"}],"author":"nosade","twitter_misc":{"Verfasst von":"nosade","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/","url":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/","name":"NOSADE Venue Merzouga - NOSADE","isPartOf":{"@id":"https:\/\/nosade.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage"},"image":{"@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage"},"thumbnailUrl":"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg","datePublished":"2018-04-19T17:10:12+00:00","dateModified":"2024-11-18T12:56:33+00:00","author":{"@id":"https:\/\/nosade.com\/de\/#\/schema\/person\/3a5e11047087029c7cd54f0a51e6695a"},"description":"DU PLANST EINE REISE NACH MERZOUGA? Wohne famili\u00e4r, im authentischen Lehmbau, in modernem Design mit sagenhaftem Blick auf die D\u00fcnen, bevor Du mit uns Deine W\u00fcstentour in den Erg Chebbi startest!","breadcrumb":{"@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nosade.com\/de\/nosade-venue-merzouga\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#primaryimage","url":"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg","contentUrl":"https:\/\/nosade.com\/wp-content\/uploads\/NOSADE-Venue-Merzouga_Source-NOSADE.jpg","width":1800,"height":720,"caption":"nosade-venue-merzouga_source-nosade"},{"@type":"BreadcrumbList","@id":"https:\/\/nosade.com\/de\/nosade-venue-merzouga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nosade.com\/de\/"},{"@type":"ListItem","position":2,"name":"Venues","item":"https:\/\/nosade.com\/de\/venues-de\/"},{"@type":"ListItem","position":3,"name":"NOSADE Venue Merzouga"}]},{"@type":"WebSite","@id":"https:\/\/nosade.com\/de\/#website","url":"https:\/\/nosade.com\/de\/","name":"NOSADE","description":"Yoga Reisen & Sahara W\u00fcstentouren f\u00fcr Nomadenherzen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nosade.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/nosade.com\/de\/#\/schema\/person\/3a5e11047087029c7cd54f0a51e6695a","name":"nosade","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nosade.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4beed8cfa39a37428b42f05072eedffb15a830a13cdeebc0e9fff810ca432ae2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4beed8cfa39a37428b42f05072eedffb15a830a13cdeebc0e9fff810ca432ae2?s=96&d=mm&r=g","caption":"nosade"},"url":"https:\/\/nosade.com\/de\/author\/nosade\/"}]}},"_links":{"self":[{"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/posts\/6563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/comments?post=6563"}],"version-history":[{"count":28,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/posts\/6563\/revisions"}],"predecessor-version":[{"id":23688,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/posts\/6563\/revisions\/23688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/media\/6564"}],"wp:attachment":[{"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/media?parent=6563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/categories?post=6563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nosade.com\/de\/wp-json\/wp\/v2\/tags?post=6563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}